{"id":213,"date":"2026-05-06T18:38:54","date_gmt":"2026-05-06T18:38:54","guid":{"rendered":"https:\/\/finance.belivedigital.com\/?p=213"},"modified":"2026-05-06T18:38:54","modified_gmt":"2026-05-06T18:38:54","slug":"o-futuro-alem-do-presente-a-construcao-de-um-legado-solido","status":"publish","type":"post","link":"https:\/\/finance.belivedigital.com\/fr\/o-futuro-alem-do-presente-a-construcao-de-um-legado-solido\/","title":{"rendered":"L&#039;avenir au-del\u00e0 du pr\u00e9sent : b\u00e2tir un h\u00e9ritage solide"},"content":{"rendered":"<html><body><p>La gestion de patrimoine est souvent per\u00e7ue uniquement sous l&#039;angle de l&#039;accumulation. L&#039;accent est mis sur les rendements mensuels, la s\u00e9lection des meilleures actions ou l&#039;investissement dans des fonds sp\u00e9cialis\u00e9s. Pourtant, un plafond invisible s\u00e9pare l&#039;investisseur moyen de l&#039;investisseur strat\u00e9gique\u00a0: la prise de conscience que le patrimoine ne doit pas seulement exister, mais se p\u00e9renniser. C&#039;est dans ce contexte qu&#039;\u00e9merge un concept essentiel, qui transforme la mani\u00e8re dont les familles g\u00e8rent leurs actifs. <strong>Le r\u00f4le de la planification successorale dans la strat\u00e9gie financi\u00e8re.<\/strong> En fin de compte, c&#039;est ce qui garantit que les efforts de toute une vie ne se dissolvent pas dans une bureaucratie ou des conflits \u00e9vitables.<\/p>\n\n\n\n<p>Une planification qui ignore l&#039;avenir est incompl\u00e8te. Imaginez construire un \u00e9difice magnifique sans pr\u00e9voir son entretien pour les d\u00e9cennies \u00e0 venir. Sans fondations solides anticipant cette transition, le patrimoine devient fragile. La p\u00e9rennit\u00e9 du patrimoine n&#039;est pas un \u00e9v\u00e9nement ponctuel survenant \u00e0 la fin de la vie\u00a0; c&#039;est une dimension strat\u00e9gique qui doit \u00eatre int\u00e9gr\u00e9e aux investissements. En professionnalisant la planification successorale, un investisseur prot\u00e8ge la liquidit\u00e9 et l&#039;int\u00e9grit\u00e9 de son patrimoine, donnant ainsi \u00e0 sa strat\u00e9gie financi\u00e8re actuelle une port\u00e9e qui d\u00e9passe le temps.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">La continuit\u00e9 des activit\u00e9s comme pilier de la strat\u00e9gie<\/h3>\n\n\n\n<p>Pour les personnes poss\u00e9dant un patrimoine important, la continuit\u00e9 ne se r\u00e9sume pas \u00e0 une simple question de r\u00e9partition. Il s&#039;agit avant tout d&#039;assurer la p\u00e9rennit\u00e9 de l&#039;activit\u00e9. Si une entreprise familiale ou un portefeuille immobilier repose exclusivement sur une seule personne pour prendre les d\u00e9cisions, le risque de paralysie op\u00e9rationnelle en son absence est consid\u00e9rable. Int\u00e9grer la succession \u00e0 la strat\u00e9gie financi\u00e8re implique de mettre en place des protocoles garantissant que les actifs continuent de g\u00e9n\u00e9rer de la valeur, quelles que soient les circonstances personnelles des fondateurs.<\/p>\n\n\n\n<p>La strat\u00e9gie financi\u00e8re moderne exige des investisseurs qu&#039;ils examinent leur bilan et se posent la question suivante : \u201c Si je ne suis plus l\u00e0 demain, cet actif sera-t-il toujours rentable, ou deviendra-t-il un fardeau pour mes h\u00e9ritiers ? \u201d R\u00e9pondre \u00e0 cette question est la premi\u00e8re \u00e9tape vers une gestion performante qui valorise la viabilit\u00e9 \u00e0 long terme.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">D\u00e9mystifier la planification de la rel\u00e8ve<\/h2>\n\n\n\n<p>Bien que le terme puisse para\u00eetre tr\u00e8s juridique, voire un peu aust\u00e8re, la planification successorale est en r\u00e9alit\u00e9 un outil d&#039;organisation et d&#039;optimisation. Elle consiste en un ensemble de mesures juridiques, fiscales et financi\u00e8res qui d\u00e9finissent les modalit\u00e9s de transmission du patrimoine. Son objectif principal est simple\u00a0: garantir le respect des volont\u00e9s du d\u00e9funt, en minimisant la charge fiscale et les d\u00e9lais de succession.<\/p>\n\n\n\n<p>Organiser le transfert de patrimoine \u00e0 l&#039;avance \u00e9vite aux familles d&#039;\u00eatre prises au d\u00e9pourvu par des proc\u00e9dures juridiques lentes et co\u00fbteuses. Au Br\u00e9sil, une succession mal planifi\u00e9e peut absorber une part consid\u00e9rable de la succession en imp\u00f4ts et frais, sans compter le blocage des comptes et des investissements pendant des mois, voire des ann\u00e9es. Lorsqu&#039;on comprend\u2026 <strong>Le r\u00f4le de la planification successorale dans la strat\u00e9gie financi\u00e8re.<\/strong>, Il appara\u00eet clairement qu&#039;il s&#039;agit de la meilleure assurance contre l&#039;inefficacit\u00e9 administrative.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">La fin des conflits et la recherche de l&#039;efficacit\u00e9<\/h3>\n\n\n\n<p>L&#039;un des principaux avantages de la planification successorale du vivant du d\u00e9funt r\u00e9side dans la pr\u00e9vention des conflits. La clart\u00e9 des r\u00e8gles de succession \u00e9limine la dimension \u00e9motionnelle qui impr\u00e8gne souvent le partage des biens. Lorsque ces r\u00e8gles sont \u00e9tablies de mani\u00e8re professionnelle et transparente, les h\u00e9ritiers deviennent des partenaires dans la pr\u00e9servation du patrimoine, et non des adversaires dans un litige.<\/p>\n\n\n\n<p>Voici une br\u00e8ve comparaison entre un processus d\u00e9sorganis\u00e9 et un plan structur\u00e9\u00a0:<\/p>\n\n\n\n<figure class=\"wp-block-table\"><table class=\"has-fixed-layout\"><thead><tr><td><strong>Aspect<\/strong><\/td><td><strong>Inventaire conventionnel<\/strong><\/td><td><strong>Planification de la succession<\/strong><\/td><\/tr><\/thead><tbody><tr><td><strong>Co\u00fbt fiscal<\/strong><\/td><td>G\u00e9n\u00e9ralement plus \u00e9lev\u00e9 (ITCMD progressif)<\/td><td>Optimis\u00e9 par le biais de structures juridiques<\/td><\/tr><tr><td><strong>Temps d&#039;ex\u00e9cution<\/strong><\/td><td>Ann\u00e9es (selon le syst\u00e8me judiciaire)<\/td><td>Imm\u00e9diat ou tr\u00e8s rapide<\/td><\/tr><tr><td><strong>Acc\u00e8s au capital<\/strong><\/td><td>Bloqu\u00e9 jusqu&#039;au partage<\/td><td>Disponibilit\u00e9 imm\u00e9diate (via des soci\u00e9t\u00e9s de portefeuille\/d&#039;assurance)<\/td><\/tr><tr><td><strong>Relations familiales<\/strong><\/td><td>Risque de frictions et de conflits.<\/td><td>Harmonie et clart\u00e9 des r\u00f4les<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">La priorit\u00e9 des investisseurs \u00e0 revenus \u00e9lev\u00e9s<\/h2>\n\n\n\n<p>Les investisseurs fortun\u00e9s n&#039;ont pas atteint ce niveau par hasard. Ils comprennent que le risque r\u00e9side non seulement dans la volatilit\u00e9 des march\u00e9s, mais aussi dans l&#039;absence de contr\u00f4le sur l&#039;\u00e9volution de leurs actifs. Pour ce type d&#039;investisseur, la pr\u00e9servation du patrimoine d&#039;une g\u00e9n\u00e9ration \u00e0 l&#039;autre est un indicateur cl\u00e9 de performance aussi important que le CDI (taux de d\u00e9p\u00f4t interbancaire br\u00e9silien) ou l&#039;IPCA (indice d&#039;inflation br\u00e9silien). La priorit\u00e9 est d&#039;\u00e9viter la \u201c\u00a0dilution du patrimoine\u00a0\u201d, un ph\u00e9nom\u00e8ne courant o\u00f9 d&#039;importantes fortunes disparaissent \u00e0 la troisi\u00e8me g\u00e9n\u00e9ration.<\/p>\n\n\n\n<p>La pr\u00e9servation du patrimoine exige une vision \u00e0 long terme. Cela implique la cr\u00e9ation de structures telles que des soci\u00e9t\u00e9s holding familiales, des fonds exclusifs ou des donations avec r\u00e9serve d&#039;usufruit. Ces outils facilitent non seulement la succession, mais offrent \u00e9galement une protection contre les risques de march\u00e9 et les responsabilit\u00e9s civiles, cr\u00e9ant ainsi un \u201c bouclier \u201d \u00e9thique et juridique autour du patrimoine constitu\u00e9.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>\u201c\u00a0Un patrimoine non durable est souvent englouti par l&#039;incertitude. La v\u00e9ritable r\u00e9ussite financi\u00e8re ne consiste pas seulement \u00e0 gagner de l&#039;argent, mais aussi \u00e0 s&#039;assurer qu&#039;il continue de profiter \u00e0 sa famille apr\u00e8s sa disparition.\u00a0\u201d<\/p>\n<\/blockquote>\n\n\n\n<h3 class=\"wp-block-heading\">R\u00e9duire les risques futurs et garantir la s\u00e9curit\u00e9 juridique<\/h3>\n\n\n\n<p>Nous vivons dans un contexte de changements l\u00e9gislatifs et fiscaux constants. Les investisseurs qui anticipent ces changements peuvent obtenir des conditions plus favorables et adapter leur structure avant l&#039;entr\u00e9e en vigueur de nouvelles r\u00e9glementations. La planification successorale joue un r\u00f4le essentiel. Elle prot\u00e8ge le patrimoine familial des risques op\u00e9rationnels, des divorces potentiels ou des difficult\u00e9s de cr\u00e9dit, garantissant ainsi la pr\u00e9servation de l&#039;essentiel du patrimoine pour les b\u00e9n\u00e9ficiaires.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Int\u00e9gration aux investissements actuels<\/h2>\n\n\n\n<p>Une erreur fr\u00e9quente consiste \u00e0 consid\u00e9rer les portefeuilles d&#039;investissement et la planification successorale comme deux choses distinctes. En r\u00e9alit\u00e9, il s&#039;agit d&#039;un seul et m\u00eame \u00e9l\u00e9ment. <strong>Le r\u00f4le de la planification successorale dans la strat\u00e9gie financi\u00e8re.<\/strong> L&#039;objectif est de veiller \u00e0 ce que chaque choix d&#039;investissement prenne en compte la facilit\u00e9 de transmission. Par exemple, investir dans l&#039;immobilier physique engendre des charges fiscales et successorales tr\u00e8s diff\u00e9rentes de celles engendr\u00e9es par un investissement dans des soci\u00e9t\u00e9s d&#039;investissement immobilier cot\u00e9es (SIIC) ou des actifs financiers liquides.<\/p>\n\n\n\n<p>Lorsque la structure du patrimoine est align\u00e9e sur la planification successorale, les investisseurs \u00e9vitent les d\u00e9cisions isol\u00e9es susceptibles d&#039;engendrer des difficult\u00e9s ult\u00e9rieures. Il est inutile d&#039;accumuler un important patrimoine immobilier si les h\u00e9ritiers ne souhaitent pas g\u00e9rer les revenus locatifs ou ne disposent pas des liquidit\u00e9s n\u00e9cessaires pour s&#039;acquitter des droits de succession. La planification int\u00e8gre ces aspects, en sugg\u00e9rant, par exemple, le recours \u00e0 des contrats d&#039;assurance-vie \u00e0 capital variable ou \u00e0 des plans d&#039;\u00e9pargne retraite priv\u00e9s (VGBL\/PGBL) comme outils de liquidit\u00e9 imm\u00e9diate pour financer la succession.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Alignement et coh\u00e9rence strat\u00e9giques<\/h3>\n\n\n\n<p>Le lien entre patrimoine et planification successorale apporte une s\u00e9r\u00e9nit\u00e9 inestimable. Lorsqu&#039;il choisit un nouvel investissement, l&#039;investisseur strat\u00e9gique se pose d&#039;embl\u00e9e les questions suivantes\u00a0: \u201c\u00a0Comment cet actif s&#039;int\u00e8gre-t-il \u00e0 mon portefeuille\u00a0? Quel sera son r\u00e9gime fiscal lors de sa transmission\u00a0?\u00a0\u201d Cette vision globale \u00e9vite que la croissance du patrimoine ne devienne un casse-t\u00eate logistique pour la g\u00e9n\u00e9ration suivante. C&#039;est la diff\u00e9rence entre laisser un h\u00e9ritage et laisser un patrimoine structur\u00e9.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Structuration et organisation claires des actifs<\/h2>\n\n\n\n<p>Une structuration claire du patrimoine est essentielle \u00e0 une planification saine. Cela implique de recenser tous vos biens\u00a0: entreprises, biens immobiliers, placements financiers, actifs \u00e0 l\u2019\u00e9tranger et m\u00eame actifs num\u00e9riques. De nombreuses familles souffrent car le patriarche ou la matriarche a conserv\u00e9 toute l\u2019information financi\u00e8re en m\u00e9moire, sans formaliser les processus ni structurer la propri\u00e9t\u00e9.<\/p>\n\n\n\n<p>La facilit\u00e9 de transmission du patrimoine d\u00e9pend de la structure de la propri\u00e9t\u00e9. Si les actifs sont regroup\u00e9s au sein d&#039;une soci\u00e9t\u00e9 holding, la succession peut s&#039;effectuer par simple transfert des actions, sans qu&#039;il soit n\u00e9cessaire de proc\u00e9der \u00e0 un inventaire judiciaire de chaque bien ou compte bancaire individuellement. Cela r\u00e9duit les tensions et permet \u00e0 la famille de se concentrer sur le deuil et la continuit\u00e9, plut\u00f4t que sur des formalit\u00e9s administratives complexes.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">R\u00e9duire l&#039;incertitude pour les h\u00e9ritiers<\/h3>\n\n\n\n<p>L&#039;incertitude engendre la peur, et la peur engendre les conflits. Lorsque les h\u00e9ritiers connaissent pr\u00e9cis\u00e9ment le plan, le niveau de stress diminue consid\u00e9rablement. Il est fondamental que les r\u00f4les de chacun soient clairement d\u00e9finis\u00a0: qui aura le droit de vote, qui recevra les dividendes, qui assurera la gestion op\u00e9rationnelle.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>D\u00e9finition des r\u00f4les\u00a0:<\/strong> Distinguer l&#039;h\u00e9ritier (celui qui re\u00e7oit l&#039;argent) et le g\u00e9rant (celui qui administre l&#039;entreprise).<\/li>\n\n\n\n<li><strong>Accords entre actionnaires\u00a0:<\/strong> \u00c9tablir des r\u00e8gles pour la sortie, l&#039;entr\u00e9e et la vente d&#039;actions.<\/li>\n\n\n\n<li><strong>Liquidit\u00e9 garantie :<\/strong> Afin de garantir la disponibilit\u00e9 des fonds n\u00e9cessaires au paiement des imp\u00f4ts sans avoir \u00e0 vendre des actifs \u00e0 des prix d\u00e9risoires.<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">L&#039;importance d&#039;une perspective \u00e0 long terme<\/h2>\n\n\n\n<p>La planification successorale n&#039;est pas une image fixe, mais un processus continu. Elle exige de l&#039;anticipation. Commencer \u00e0 planifier \u00e0 40 ans est bien plus efficace et \u00e9conomique que d&#039;attendre 70 ans. Le temps permet de mettre en place des strat\u00e9gies de donation progressives, de tirer parti des abattements annuels et de former progressivement les h\u00e9ritiers \u00e0 la gestion du patrimoine.<\/p>\n\n\n\n<p>Une strat\u00e9gie continue implique des r\u00e9visions p\u00e9riodiques. La famille s&#039;est-elle agrandie\u00a0? Y a-t-il eu un divorce\u00a0? Une nouvelle entreprise a-t-elle \u00e9t\u00e9 cr\u00e9\u00e9e\u00a0? La planification doit s&#039;adapter \u00e0 ces changements. Un plan \u00e9labor\u00e9 il y a dix ans peut ne plus \u00eatre adapt\u00e9 \u00e0 la situation actuelle. La rigueur n\u00e9cessaire pour r\u00e9viser le plan de succession est ce qui distingue les familles prosp\u00e8res de celles qui ont simplement eu de la chance pendant un temps.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Examen et mise \u00e0 jour\u00a0: Le forfait Vivo<\/h3>\n\n\n\n<p>Les modifications de la l\u00e9gislation fiscale, telles que les changements des taux de droits de succession, sont des motifs fr\u00e9quents de r\u00e9vision. Par ailleurs, l&#039;\u00e9volution de la dynamique familiale, comme la naissance de petits-enfants ou l&#039;installation d&#039;un h\u00e9ritier \u00e0 l&#039;\u00e9tranger, a un impact direct sur l&#039;efficacit\u00e9 du plan. La mise \u00e0 jour r\u00e9guli\u00e8re du plan garantit que la strat\u00e9gie financi\u00e8re reste optimis\u00e9e pour la situation actuelle, tout en gardant un \u0153il sur l&#039;avenir.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">La planification dans le cadre de la gestion d&#039;actifs<\/h2>\n\n\n\n<p>Int\u00e9grer la planification successorale \u00e0 la gestion quotidienne du patrimoine exige un changement de mentalit\u00e9. Il ne s&#039;agit plus de \u201c gagner la partie \u201d aujourd&#039;hui, mais de garantir la p\u00e9rennit\u00e9 du succ\u00e8s. La continuit\u00e9 doit \u00eatre l&#039;objectif ultime de toute strat\u00e9gie pour les personnes fortun\u00e9es.<\/p>\n\n\n\n<p>Lorsque nous consid\u00e9rons la succession comme un prolongement naturel de la planification financi\u00e8re, nous levons le tabou. Parler d&#039;h\u00e9ritage et de succession devient alors une preuve d&#039;attention et d&#039;amour envers la famille. C&#039;est la mani\u00e8re la plus concr\u00e8te de dire\u00a0: \u201c\u00a0Je tiens tellement \u00e0 toi que j&#039;ai d\u00e9j\u00e0 tout organis\u00e9 pour que tu n&#039;aies aucun souci \u00e0 l&#039;avenir.\u00a0\u201d.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Conclusion et vision strat\u00e9gique<\/h3>\n\n\n\n<p>Tout au long de cet article, nous avons vu que <strong>Le r\u00f4le de la planification successorale dans la strat\u00e9gie financi\u00e8re.<\/strong> Cela va bien au-del\u00e0 de la bureaucratie. C&#039;est un outil de libert\u00e9. Libert\u00e9 pour l&#039;investisseur, qui sait que ses souhaits seront respect\u00e9s, et libert\u00e9 pour les h\u00e9ritiers, qui b\u00e9n\u00e9ficient d&#039;un chemin tout trac\u00e9 au lieu d&#039;un labyrinthe d&#039;incertitudes.<\/p>\n\n\n\n<p>Pr\u00e9parer son avenir financier, c&#039;est comprendre que le patrimoine est un flux, et non un stock statique. Avec de l&#039;organisation, de l&#039;anticipation et les structures ad\u00e9quates, il est possible de transformer la r\u00e9ussite financi\u00e8re d&#039;une vie en un h\u00e9ritage durable pour plusieurs g\u00e9n\u00e9rations. La strat\u00e9gie s&#039;arr\u00eate-t-elle l\u00e0 o\u00f9 commence la succession\u00a0? Au contraire\u00a0: la succession est le crit\u00e8re d\u00e9cisif qui prouve que la strat\u00e9gie a bel et bien port\u00e9 ses fruits.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">\u00c9l\u00e9ments cl\u00e9s pour une planification r\u00e9ussie<\/h3>\n\n\n\n<ol start=\"1\" class=\"wp-block-list\">\n<li><strong>Diagnostic des actifs\u00a0:<\/strong> Inventaire d\u00e9taill\u00e9 de tous les actifs et passifs.<\/li>\n\n\n\n<li><strong>Analyse familiale :<\/strong> Comprendre la dynamique entre les h\u00e9ritiers et leurs aptitudes.<\/li>\n\n\n\n<li><strong>Choisir les outils\u00a0:<\/strong> Distinguer entre soci\u00e9t\u00e9 holding, donation, assurance et testament.<\/li>\n\n\n\n<li><strong>Mise en \u0153uvre juridique :<\/strong> R\u00e9daction de contrats, de modifications de contrats et d&#039;actes.<\/li>\n\n\n\n<li><strong>Surveillance:<\/strong> Examen annuel ou bisannuel du plan pour proc\u00e9der aux ajustements n\u00e9cessaires.<\/li>\n<\/ol>\n\n\n\n<p>Investir, c&#039;est se concentrer sur le pr\u00e9sent\u00a0; planifier sa succession, c&#039;est s&#039;assurer la p\u00e9rennit\u00e9 de ses efforts. Il est important d&#039;aborder ce sujet non pas lorsque l&#039;avenir est incertain, mais lorsque le pr\u00e9sent est suffisamment stable pour m\u00e9riter d&#039;\u00eatre prot\u00e9g\u00e9. La v\u00e9ritable intelligence financi\u00e8re r\u00e9side dans la capacit\u00e9 \u00e0 voir au-del\u00e0 de ses propres perspectives.<\/p>\n<\/body><\/html>","protected":false},"excerpt":{"rendered":"<p>Muitas vezes, a gest\u00e3o de grandes fortunas \u00e9 vista apenas sob a \u00f3tica da acumula\u00e7\u00e3o. O foco reside na rentabilidade mensal, na escolha da melhor a\u00e7\u00e3o ou no aporte em fundos exclusivos. No entanto, existe um teto invis\u00edvel que separa o investidor comum do investidor estrat\u00e9gico: a compreens\u00e3o de que o patrim\u00f4nio n\u00e3o deve apenas [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":214,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-213","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-financas"],"_links":{"self":[{"href":"https:\/\/finance.belivedigital.com\/fr\/wp-json\/wp\/v2\/posts\/213","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/finance.belivedigital.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/finance.belivedigital.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/finance.belivedigital.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/finance.belivedigital.com\/fr\/wp-json\/wp\/v2\/comments?post=213"}],"version-history":[{"count":1,"href":"https:\/\/finance.belivedigital.com\/fr\/wp-json\/wp\/v2\/posts\/213\/revisions"}],"predecessor-version":[{"id":215,"href":"https:\/\/finance.belivedigital.com\/fr\/wp-json\/wp\/v2\/posts\/213\/revisions\/215"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/finance.belivedigital.com\/fr\/wp-json\/wp\/v2\/media\/214"}],"wp:attachment":[{"href":"https:\/\/finance.belivedigital.com\/fr\/wp-json\/wp\/v2\/media?parent=213"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/finance.belivedigital.com\/fr\/wp-json\/wp\/v2\/categories?post=213"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/finance.belivedigital.com\/fr\/wp-json\/wp\/v2\/tags?post=213"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}