{"id":59,"count":2,"description":"","link":"https:\/\/finance.belivedigital.com\/ja\/tag\/cartao-de-credito-online\/","name":"cart\u00e3o de cr\u00e9dito online","slug":"cartao-de-credito-online","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/finance.belivedigital.com\/ja\/wp-json\/wp\/v2\/tags\/59","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/finance.belivedigital.com\/ja\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/finance.belivedigital.com\/ja\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/finance.belivedigital.com\/ja\/wp-json\/wp\/v2\/posts?tags=59"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}