{"id":60,"count":2,"description":"","link":"https:\/\/finance.belivedigital.com\/ko\/tag\/cartao-de-credito-italia\/","name":"\uc774\ud0c8\ub9ac\uc544 \uc2e0\uc6a9\uce74\ub4dc","slug":"cartao-de-credito-italia","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/finance.belivedigital.com\/ko\/wp-json\/wp\/v2\/tags\/60","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/finance.belivedigital.com\/ko\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/finance.belivedigital.com\/ko\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/finance.belivedigital.com\/ko\/wp-json\/wp\/v2\/posts?tags=60"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}